{"id":122,"date":"2015-04-06T21:05:05","date_gmt":"2015-04-07T00:05:05","guid":{"rendered":"http:\/\/eimargentina.com\/blog\/?p=122"},"modified":"2015-04-06T21:05:05","modified_gmt":"2015-04-07T00:05:05","slug":"coca-cola-anuncia-su-colaboracion-con-eim-argentina","status":"publish","type":"post","link":"http:\/\/eimargentina.com\/blog\/coca-cola-anuncia-su-colaboracion-con-eim-argentina\/","title":{"rendered":"Coca-Cola anuncia su colaboraci\u00f3n con EIM Argentina"},"content":{"rendered":"<p style=\"text-align: center;\">El pasado Noviembre, Coca-Cola anunci\u00f3 que colaborar\u00e1 con EIM Argentina para promocionar la actividad f\u00edsica como un compromiso a un estilo de vida activo y saludable.<\/p>\n<p>[aesop_image img=\u00bbhttp:\/\/eimargentina.com\/blog\/wp-content\/uploads\/2015\/04\/10665851_384696035013217_5938454885489965167_n-1-1.jpg\u00bb align=\u00bbleft\u00bb lightbox=\u00bbon\u00bb caption=\u00bbCr\u00e9dito: Compa\u00f1\u00eda Coca-Cola\u00bb captionposition=\u00bbleft\u00bb]<\/p>\n<p>La reuni\u00f3n cont\u00f3 con la presencia del Dr. Jorge Franchella, director del programa Actividad F\u00edsica y Deportes del Hospital de Cl\u00ednicas de la UBA y la destacada Dra. Sandra Mahecha, Directora General del Centro de Estudos do Labot\u00f3rio de\u00a0<span class=\"Apple-style-span\">Aptid\u00e3o F\u00edsica de S\u00e3o Caetano do Sul\u00a0\u2013 CELAFISCS, y asesora cientif\u00edca del Programa de Promoci\u00f3n de Actividad F\u00edsica\u00a0Agita S\u00e3o Paulo\u00a0de la Secretar\u00eda de Estado de Salud del Estado de S\u00e3o Paulo \u2013 Brasil.<\/span><\/p>\n<blockquote><p>\u201cEn Coca-Cola estamos comprometidos con la promoci\u00f3n de la actividad f\u00edsica a trav\u00e9s de diversas iniciativas y programas. Sabemos que el combate al sedentarismo es una pieza clave para lograr el bienestar y la adopci\u00f3n de estilos de vida saludables. Nuestra alianza estrat\u00e9gica internacional con Exercise is Medicine desde 2007 pone en evidencia este compromiso integral y de largo plazo para lograr el gran desaf\u00edo de que la pr\u00e1ctica de actividad f\u00edsica se instale en la poblaci\u00f3n. Estamos convencidos que los cambios positivos y duraderos deben involucrar el esfuerzo mancomunado del sector privado, el sector p\u00fablico y la sociedad civil\u201d . Soledad Izquierdo,\u00a0<span class=\"Apple-style-span\">Vicepresidente de Asuntos P\u00fablicos y Comunicaciones de Coca-Cola para el Sur de Am\u00e9rica Latina.<\/span><\/p><\/blockquote>\n<p>Mir\u00e1 el art\u00edculo original a trav\u00e9s de \u00e9ste <a href=\"http:\/\/www.cocacoladeargentina.com.ar\/prensa\/llega-exercise-is-medicine-programa-que-ensena-a-prescribir-actividad-fisica\/\" target=\"_blank\">link\u00a0<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El pasado Noviembre, Coca-Cola anunci\u00f3 que colaborar\u00e1 con EIM Argentina para promocionar la actividad f\u00edsica como un compromiso a un estilo de vida activo y saludable. [aesop_image img=\u00bbhttp:\/\/eimargentina.com\/blog\/wp-content\/uploads\/2015\/04\/10665851_384696035013217_5938454885489965167_n-1-1.jpg\u00bb align=\u00bbleft\u00bb lightbox=\u00bbon\u00bb caption=\u00bbCr\u00e9dito: Compa\u00f1\u00eda Coca-Cola\u00bb captionposition=\u00bbleft\u00bb] La reuni\u00f3n cont\u00f3 con la presencia del Dr. Jorge Franchella, director del programa Actividad F\u00edsica y Deportes del Hospital de Cl\u00ednicas [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":120,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[8,21,31,43,50,69,122],"class_list":["post-122","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-actividad","tag-beneficios","tag-coca-cola","tag-destacado","tag-eim","tag-fisica","tag-programa"],"_links":{"self":[{"href":"http:\/\/eimargentina.com\/blog\/wp-json\/wp\/v2\/posts\/122","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/eimargentina.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/eimargentina.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/eimargentina.com\/blog\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/eimargentina.com\/blog\/wp-json\/wp\/v2\/comments?post=122"}],"version-history":[{"count":0,"href":"http:\/\/eimargentina.com\/blog\/wp-json\/wp\/v2\/posts\/122\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/eimargentina.com\/blog\/wp-json\/wp\/v2\/media\/120"}],"wp:attachment":[{"href":"http:\/\/eimargentina.com\/blog\/wp-json\/wp\/v2\/media?parent=122"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/eimargentina.com\/blog\/wp-json\/wp\/v2\/categories?post=122"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/eimargentina.com\/blog\/wp-json\/wp\/v2\/tags?post=122"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}